{"id":1354,"date":"2016-02-18T16:02:07","date_gmt":"2016-02-18T16:02:07","guid":{"rendered":"http:\/\/equipes.nelsoncardeira.com\/?p=1354"},"modified":"2016-02-18T16:02:07","modified_gmt":"2016-02-18T16:02:07","slug":"quilometro-zero-para-o-encontro-internacional-em-2018","status":"publish","type":"post","link":"https:\/\/equipes-notre-dame.com\/es\/kilometro-cero-de-la-encuentro-internacional-en-2018\/","title":{"rendered":"Kil\u00f3metro cero de la encuentro internacional en 2018"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/iwrMBAft1E4\" width=\"640\" height=\"360\" frameborder=\"0\" scrolling=\"no\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<h5><\/h5>\n<h5>\u00a0\u00a1Informe sobre F\u00e1tima 2018 !<\/h5>\n<p>En 2018, el XXII encuentro internacional de los Equipos de Nuestra Se\u00f1ora tendr\u00e1 lugar en F\u00e1tima.<br \/>\nEl encuentro internacional es una tradici\u00f3n : cada seis a\u00f1os los equipistas del mundo entero se encuentran en un lugar diferente : Roma, Lourdes, F\u00e1tima, Santiago de Compostela, Brasilia&#8230; Cada vez, de Bogot\u00e1 Sidney pasando por Sao Paulo, Varsovia, Beirut o Yound\u00e9, miles de equipistas deciden ponerse en ruta para compartir su alegr\u00eda y su voluntad de seguir en pareja, el camino trazado por Cristo.<br \/>\nSon m\u00e1s de 8.000 equipistas que intercambia, se encuentran y oran juntos, cada uno en su propio idioma, cada uno con su propia cultura, \u00a1pero todos con el mismo Cristo presente entre ellos\u2026. !<br \/>\n\u00a1Quien no ha vivido tales momentos de fervor y convivencia compartidos no sabe lo mucho que un Movimiento Internacional como los Equipos de Nuestra Se\u00f1ora puede aportarle !<br \/>\nSiempre es un momento de fraternidad y esperanza.<\/p>\n<h3><a href=\"https:\/\/www.flickr.com\/photos\/135756894@N05\/albums\/72157659075952013\">\u00a1Y ahora, todos en camino hacia F\u00e1tima 2018 !<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a1Informe sobre F\u00e1tima 2018 ! En 2018, el XXII encuentro internacional de los Equipos de Nuestra Se\u00f1ora tendr\u00e1 lugar en F\u00e1tima. El encuentro internacional es una tradici\u00f3n : cada seis a\u00f1os los equipistas del mundo entero se encuentran en un lugar diferente : Roma, Lourdes, F\u00e1tima, Santiago de Compostela, Brasilia&#8230; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"es","enabled_languages":["fr","pt","es","it","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":true},"es":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/posts\/1354"}],"collection":[{"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/comments?post=1354"}],"version-history":[{"count":0,"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/posts\/1354\/revisions"}],"wp:attachment":[{"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/media?parent=1354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/categories?post=1354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equipes-notre-dame.com\/es\/wp-json\/wp\/v2\/tags?post=1354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}